{"id":1011,"date":"2008-10-01T13:00:11","date_gmt":"2008-10-01T12:00:11","guid":{"rendered":"http:\/\/www.judithsanders.nl\/site\/?p=1011"},"modified":"2008-10-01T13:00:11","modified_gmt":"2008-10-01T12:00:11","slug":"cspine-concept-flashdemo","status":"publish","type":"post","link":"https:\/\/judithsanders.nl\/website\/index.php\/2008\/10\/01\/cspine-concept-flashdemo\/","title":{"rendered":"Website concept \/ Flashdemo Cspine"},"content":{"rendered":"<p>In opdracht van The Communication Force heb ik deze opdracht uitgevoerd.<\/p>\n<p>Cspine is een applicatie voor Live! contact met bezoekers van uw website via chat, video (webcam) en voice, dit volledig webbased.<\/p>\n<ul>\n<li>Adobe Photoshop<\/li>\n<li>Adobe Flash<\/li>\n<\/ul>\n<p><em>2008 Ontwerp en flash mockup demonstratie.<\/em><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" alt=\"cspine1\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2008\/10\/cspine1.jpg\" width=\"532\" height=\"300\" \/><br \/>\n<img decoding=\"async\" alt=\"cspine2\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2008\/10\/cspine2.jpg\" width=\"528\" height=\"300\" \/><br \/>\n<img decoding=\"async\" alt=\"cspine3\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2008\/10\/cspine3.jpg\" width=\"532\" height=\"300\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In opdracht van The Communication Force heb ik deze opdracht uitgevoerd. Cspine is een applicatie voor Live! contact met bezoekers&#8230; <\/p>\n<div class=\"art-el-more\"><a href=\"https:\/\/judithsanders.nl\/website\/index.php\/2008\/10\/01\/cspine-concept-flashdemo\/\" class=\"art-link art-color-link art-w-chevron\">Read more<\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[43],"tags":[],"class_list":["post-1011","post","type-post","status-publish","format-standard","hentry","category-diversen"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"In opdracht van The Communication Force heb ik deze opdracht uitgevoerd. Cspine is een applicatie voor Live! contact met bezoekers van uw website via chat, video (webcam) en voice, dit volledig webbased. Adobe Photoshop Adobe Flash 2008 Ontwerp en flash mockup demonstratie.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"WO6NTrPSlDMSbKVdm2D1-_LuA9xh_r0XoPxxl90knfQ\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/judithsanders.nl\/website\/index.php\/2008\/10\/01\/cspine-concept-flashdemo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Judith Sanders MultiMedia &amp; e-Learning - Freelance e-Learning designer and developer\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Website concept \/ Flashdemo Cspine - Judith Sanders MultiMedia &amp; e-Learning\" \/>\n\t\t<meta property=\"og:description\" content=\"In opdracht van The Communication Force heb ik deze opdracht uitgevoerd. Cspine is een applicatie voor Live! contact met bezoekers van uw website via chat, video (webcam) en voice, dit volledig webbased. Adobe Photoshop Adobe Flash 2008 Ontwerp en flash mockup demonstratie.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/judithsanders.nl\/website\/index.php\/2008\/10\/01\/cspine-concept-flashdemo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1039\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1060\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2008-10-01T12:00:11+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2008-10-01T12:00:11+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Website concept \/ Flashdemo Cspine - Judith Sanders MultiMedia &amp; e-Learning\" \/>\n\t\t<meta name=\"twitter:description\" content=\"In opdracht van The Communication Force heb ik deze opdracht uitgevoerd. Cspine is een applicatie voor Live! contact met bezoekers van uw website via chat, video (webcam) en voice, dit volledig webbased. Adobe Photoshop Adobe Flash 2008 Ontwerp en flash mockup demonstratie.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2008\\\/10\\\/01\\\/cspine-concept-flashdemo\\\/#blogposting\",\"name\":\"Website concept \\\/ Flashdemo Cspine - Judith Sanders MultiMedia & e-Learning\",\"headline\":\"Website concept \\\/ Flashdemo Cspine\",\"author\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.judithsanders.nl\\\/site\\\/wp-content\\\/uploads\\\/2008\\\/10\\\/cspine1.jpg\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2008\\\/10\\\/01\\\/cspine-concept-flashdemo\\\/#articleImage\"},\"datePublished\":\"2008-10-01T13:00:11+01:00\",\"dateModified\":\"2008-10-01T13:00:11+01:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2008\\\/10\\\/01\\\/cspine-concept-flashdemo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2008\\\/10\\\/01\\\/cspine-concept-flashdemo\\\/#webpage\"},\"articleSection\":\"Diversen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2008\\\/10\\\/01\\\/cspine-concept-flashdemo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/judithsanders.nl\\\/website\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/category\\\/diversen\\\/#listItem\",\"name\":\"Diversen\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/category\\\/diversen\\\/#listItem\",\"position\":2,\"name\":\"Diversen\",\"item\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/category\\\/diversen\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2008\\\/10\\\/01\\\/cspine-concept-flashdemo\\\/#listItem\",\"name\":\"Website concept \\\/ Flashdemo Cspine\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2008\\\/10\\\/01\\\/cspine-concept-flashdemo\\\/#listItem\",\"position\":3,\"name\":\"Website concept \\\/ Flashdemo Cspine\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/category\\\/diversen\\\/#listItem\",\"name\":\"Diversen\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#organization\",\"name\":\"Judith Sanders MultiMedia & e-Learning\",\"description\":\"Freelance e-Learning designer and developer Totaaloplossing e-Learning Naast mijn design competenties lever ik diverse nevendiensten die samen een allround servicepakket opleveren om alle e-Learning en andere diverse digitale projecten perfect op te kunnen leveren, al dan niet in partnership. Design wordt als \\u00e9\\u00e9n van de hoofddisciplines aangeboden, waarbij het eindresultaat gebruiksvriendelijk is en professioneel oogt. Het is intu\\u00eftief en spreekt de beoogde doelgroep aan. Technisch ben ik competent en is er weinig wat niet kan in mijn beleving. Mocht het nodig zijn dan kan ik altijd nog iemand uit mijn netwerk inschakelen om het project extra kracht bij te zetten. Mijn toegevoegde waarde is luisteren naar uw wensen en deze optimaal vertalen naar het product van uw keuze.\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/\",\"telephone\":\"+31652460068\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo_judithsanders_grijsverloop.png\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2008\\\/10\\\/01\\\/cspine-concept-flashdemo\\\/#organizationLogo\",\"width\":1039,\"height\":1060},\"image\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2008\\\/10\\\/01\\\/cspine-concept-flashdemo\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/judithsanders\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/#author\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2008\\\/10\\\/01\\\/cspine-concept-flashdemo\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fca062c59add9c0becf05d336fedb615de736cc5a007bc2c39f46bb848991a1b?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2008\\\/10\\\/01\\\/cspine-concept-flashdemo\\\/#webpage\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2008\\\/10\\\/01\\\/cspine-concept-flashdemo\\\/\",\"name\":\"Website concept \\\/ Flashdemo Cspine - Judith Sanders MultiMedia & e-Learning\",\"description\":\"In opdracht van The Communication Force heb ik deze opdracht uitgevoerd. Cspine is een applicatie voor Live! contact met bezoekers van uw website via chat, video (webcam) en voice, dit volledig webbased. Adobe Photoshop Adobe Flash 2008 Ontwerp en flash mockup demonstratie.\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2008\\\/10\\\/01\\\/cspine-concept-flashdemo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/#author\"},\"datePublished\":\"2008-10-01T13:00:11+01:00\",\"dateModified\":\"2008-10-01T13:00:11+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#website\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/\",\"name\":\"Judith Sanders MultiMedia & e-Learning\",\"description\":\"Freelance e-Learning designer and developer\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Website concept \/ Flashdemo Cspine - Judith Sanders MultiMedia & e-Learning","description":"In opdracht van The Communication Force heb ik deze opdracht uitgevoerd. Cspine is een applicatie voor Live! contact met bezoekers van uw website via chat, video (webcam) en voice, dit volledig webbased. Adobe Photoshop Adobe Flash 2008 Ontwerp en flash mockup demonstratie.","canonical_url":"https:\/\/judithsanders.nl\/website\/index.php\/2008\/10\/01\/cspine-concept-flashdemo\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"WO6NTrPSlDMSbKVdm2D1-_LuA9xh_r0XoPxxl90knfQ","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2008\/10\/01\/cspine-concept-flashdemo\/#blogposting","name":"Website concept \/ Flashdemo Cspine - Judith Sanders MultiMedia & e-Learning","headline":"Website concept \/ Flashdemo Cspine","author":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/#author"},"publisher":{"@id":"https:\/\/judithsanders.nl\/website\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2008\/10\/cspine1.jpg","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2008\/10\/01\/cspine-concept-flashdemo\/#articleImage"},"datePublished":"2008-10-01T13:00:11+01:00","dateModified":"2008-10-01T13:00:11+01:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/2008\/10\/01\/cspine-concept-flashdemo\/#webpage"},"isPartOf":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/2008\/10\/01\/cspine-concept-flashdemo\/#webpage"},"articleSection":"Diversen"},{"@type":"BreadcrumbList","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2008\/10\/01\/cspine-concept-flashdemo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website#listItem","position":1,"name":"Home","item":"https:\/\/judithsanders.nl\/website","nextItem":{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/category\/diversen\/#listItem","name":"Diversen"}},{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/category\/diversen\/#listItem","position":2,"name":"Diversen","item":"https:\/\/judithsanders.nl\/website\/index.php\/category\/diversen\/","nextItem":{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2008\/10\/01\/cspine-concept-flashdemo\/#listItem","name":"Website concept \/ Flashdemo Cspine"},"previousItem":{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2008\/10\/01\/cspine-concept-flashdemo\/#listItem","position":3,"name":"Website concept \/ Flashdemo Cspine","previousItem":{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/category\/diversen\/#listItem","name":"Diversen"}}]},{"@type":"Organization","@id":"https:\/\/judithsanders.nl\/website\/#organization","name":"Judith Sanders MultiMedia & e-Learning","description":"Freelance e-Learning designer and developer Totaaloplossing e-Learning Naast mijn design competenties lever ik diverse nevendiensten die samen een allround servicepakket opleveren om alle e-Learning en andere diverse digitale projecten perfect op te kunnen leveren, al dan niet in partnership. Design wordt als \u00e9\u00e9n van de hoofddisciplines aangeboden, waarbij het eindresultaat gebruiksvriendelijk is en professioneel oogt. Het is intu\u00eftief en spreekt de beoogde doelgroep aan. Technisch ben ik competent en is er weinig wat niet kan in mijn beleving. Mocht het nodig zijn dan kan ik altijd nog iemand uit mijn netwerk inschakelen om het project extra kracht bij te zetten. Mijn toegevoegde waarde is luisteren naar uw wensen en deze optimaal vertalen naar het product van uw keuze.","url":"https:\/\/judithsanders.nl\/website\/","telephone":"+31652460068","logo":{"@type":"ImageObject","url":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2008\/10\/01\/cspine-concept-flashdemo\/#organizationLogo","width":1039,"height":1060},"image":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/2008\/10\/01\/cspine-concept-flashdemo\/#organizationLogo"},"sameAs":["https:\/\/www.linkedin.com\/in\/judithsanders\/"]},{"@type":"Person","@id":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/#author","url":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2008\/10\/01\/cspine-concept-flashdemo\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/fca062c59add9c0becf05d336fedb615de736cc5a007bc2c39f46bb848991a1b?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2008\/10\/01\/cspine-concept-flashdemo\/#webpage","url":"https:\/\/judithsanders.nl\/website\/index.php\/2008\/10\/01\/cspine-concept-flashdemo\/","name":"Website concept \/ Flashdemo Cspine - Judith Sanders MultiMedia & e-Learning","description":"In opdracht van The Communication Force heb ik deze opdracht uitgevoerd. Cspine is een applicatie voor Live! contact met bezoekers van uw website via chat, video (webcam) en voice, dit volledig webbased. Adobe Photoshop Adobe Flash 2008 Ontwerp en flash mockup demonstratie.","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/judithsanders.nl\/website\/#website"},"breadcrumb":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/2008\/10\/01\/cspine-concept-flashdemo\/#breadcrumblist"},"author":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/#author"},"creator":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/#author"},"datePublished":"2008-10-01T13:00:11+01:00","dateModified":"2008-10-01T13:00:11+01:00"},{"@type":"WebSite","@id":"https:\/\/judithsanders.nl\/website\/#website","url":"https:\/\/judithsanders.nl\/website\/","name":"Judith Sanders MultiMedia & e-Learning","description":"Freelance e-Learning designer and developer","inLanguage":"en-US","publisher":{"@id":"https:\/\/judithsanders.nl\/website\/#organization"}}]},"og:locale":"en_US","og:site_name":"Judith Sanders MultiMedia &amp; e-Learning - Freelance e-Learning designer and developer","og:type":"article","og:title":"Website concept \/ Flashdemo Cspine - Judith Sanders MultiMedia &amp; e-Learning","og:description":"In opdracht van The Communication Force heb ik deze opdracht uitgevoerd. Cspine is een applicatie voor Live! contact met bezoekers van uw website via chat, video (webcam) en voice, dit volledig webbased. Adobe Photoshop Adobe Flash 2008 Ontwerp en flash mockup demonstratie.","og:url":"https:\/\/judithsanders.nl\/website\/index.php\/2008\/10\/01\/cspine-concept-flashdemo\/","og:image":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png","og:image:secure_url":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png","og:image:width":1039,"og:image:height":1060,"article:published_time":"2008-10-01T12:00:11+00:00","article:modified_time":"2008-10-01T12:00:11+00:00","twitter:card":"summary_large_image","twitter:title":"Website concept \/ Flashdemo Cspine - Judith Sanders MultiMedia &amp; e-Learning","twitter:description":"In opdracht van The Communication Force heb ik deze opdracht uitgevoerd. Cspine is een applicatie voor Live! contact met bezoekers van uw website via chat, video (webcam) en voice, dit volledig webbased. Adobe Photoshop Adobe Flash 2008 Ontwerp en flash mockup demonstratie.","twitter:image":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png"},"aioseo_meta_data":{"post_id":"1011","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-01-23 21:48:01","updated":"2025-06-04 14:18:05","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/judithsanders.nl\/website\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/judithsanders.nl\/website\/index.php\/category\/diversen\/\" title=\"Diversen\">Diversen<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tWebsite concept \/ Flashdemo Cspine\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/judithsanders.nl\/website"},{"label":"Diversen","link":"https:\/\/judithsanders.nl\/website\/index.php\/category\/diversen\/"},{"label":"Website concept \/ Flashdemo Cspine","link":"https:\/\/judithsanders.nl\/website\/index.php\/2008\/10\/01\/cspine-concept-flashdemo\/"}],"_links":{"self":[{"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/posts\/1011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/comments?post=1011"}],"version-history":[{"count":0,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/posts\/1011\/revisions"}],"wp:attachment":[{"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/media?parent=1011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/categories?post=1011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/tags?post=1011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}