{"id":1650,"date":"2013-01-08T11:15:31","date_gmt":"2013-01-08T10:15:31","guid":{"rendered":"http:\/\/www.judithsanders.nl\/site\/?p=1650"},"modified":"2013-01-08T11:15:31","modified_gmt":"2013-01-08T10:15:31","slug":"huisstijl-tandartspraktijk-tivoli-ilovit","status":"publish","type":"post","link":"https:\/\/judithsanders.nl\/website\/index.php\/2013\/01\/08\/huisstijl-tandartspraktijk-tivoli-ilovit\/","title":{"rendered":"Huisstijl Tandartspraktijk Tivoli \/ iloviT"},"content":{"rendered":"<p>Voor Tandartspraktijk Tivoli ben ik begonnen met het ontwikkelen van een website in combinatie met het redesign van het logo. Nadat de website is gelanceerd zijn ook diverse huisstijlelementen onder handen genomen waaronder de visitekaartjes, het briefpapier, een variatie in enveloppen, with compliments kaarten en 3 soorten afsprakenkaartjes.<\/p>\n<p>De website kunt u ook <span style=\"text-decoration: underline;\"><a title=\"Website item portfolio Tandartspraktijk Tivoli\" href=\"http:\/\/www.judithsanders.nl\/site\/website-tandartspraktijk-tivoli\/\">hier binnen de portfolio<\/a><\/span> bekijken.<\/p>\n<ul>\n<li>Adobe Illustrator<\/li>\n<li>Adobe Photoshop<\/li>\n<\/ul>\n<p><em>Ontwerp en ontwikkeling 2012.<\/em><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" alt=\"TPT_LOGO\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2012\/06\/TPT_LOGO.jpg\" width=\"532\" height=\"300\" \/><br \/>\n<img decoding=\"async\" alt=\"TPT1\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2013\/02\/TPT11.jpg\" width=\"532\" height=\"338\" \/><br \/>\n<img decoding=\"async\" alt=\"TPT2\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2013\/02\/TPT21.jpg\" width=\"532\" height=\"300\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" alt=\"TPT_klapkaartje1\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2013\/02\/TPT_klapkaartje1.jpg\" width=\"532\" height=\"300\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" alt=\"TPT_klapkaartje2\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2013\/02\/TPT_klapkaartje2.jpg\" width=\"532\" height=\"300\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" alt=\"TPT3_left\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2013\/02\/TPT3_left.jpg\" width=\"532\" height=\"300\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" alt=\"TPT_klapkaartje3\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2013\/01\/TPT_klapkaartje3.jpg\" width=\"532\" height=\"300\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voor Tandartspraktijk Tivoli ben ik begonnen met het ontwikkelen van een website in combinatie met het redesign van het logo&#8230;. <\/p>\n<div class=\"art-el-more\"><a href=\"https:\/\/judithsanders.nl\/website\/index.php\/2013\/01\/08\/huisstijl-tandartspraktijk-tivoli-ilovit\/\" class=\"art-link art-color-link art-w-chevron\">Read more<\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[41,44],"tags":[],"class_list":["post-1650","post","type-post","status-publish","format-standard","hentry","category-drukwerk","category-huisstijlen"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Voor Tandartspraktijk Tivoli ben ik begonnen met het ontwikkelen van een website in combinatie met het redesign van het logo. Nadat de website is gelanceerd zijn ook diverse huisstijlelementen onder handen genomen waaronder de visitekaartjes, het briefpapier, een variatie in enveloppen, with compliments kaarten en 3 soorten afsprakenkaartjes. De website kunt u ook hier binnen\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"WO6NTrPSlDMSbKVdm2D1-_LuA9xh_r0XoPxxl90knfQ\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/judithsanders.nl\/website\/index.php\/2013\/01\/08\/huisstijl-tandartspraktijk-tivoli-ilovit\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Judith Sanders MultiMedia &amp; e-Learning - Freelance e-Learning designer and developer\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Huisstijl Tandartspraktijk Tivoli \/ iloviT - Judith Sanders MultiMedia &amp; e-Learning\" \/>\n\t\t<meta property=\"og:description\" content=\"Voor Tandartspraktijk Tivoli ben ik begonnen met het ontwikkelen van een website in combinatie met het redesign van het logo. Nadat de website is gelanceerd zijn ook diverse huisstijlelementen onder handen genomen waaronder de visitekaartjes, het briefpapier, een variatie in enveloppen, with compliments kaarten en 3 soorten afsprakenkaartjes. De website kunt u ook hier binnen\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/judithsanders.nl\/website\/index.php\/2013\/01\/08\/huisstijl-tandartspraktijk-tivoli-ilovit\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1039\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1060\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2013-01-08T10:15:31+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2013-01-08T10:15:31+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Huisstijl Tandartspraktijk Tivoli \/ iloviT - Judith Sanders MultiMedia &amp; e-Learning\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Voor Tandartspraktijk Tivoli ben ik begonnen met het ontwikkelen van een website in combinatie met het redesign van het logo. Nadat de website is gelanceerd zijn ook diverse huisstijlelementen onder handen genomen waaronder de visitekaartjes, het briefpapier, een variatie in enveloppen, with compliments kaarten en 3 soorten afsprakenkaartjes. De website kunt u ook hier binnen\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2013\\\/01\\\/08\\\/huisstijl-tandartspraktijk-tivoli-ilovit\\\/#blogposting\",\"name\":\"Huisstijl Tandartspraktijk Tivoli \\\/ iloviT - Judith Sanders MultiMedia & e-Learning\",\"headline\":\"Huisstijl Tandartspraktijk Tivoli \\\/ iloviT\",\"author\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.judithsanders.nl\\\/site\\\/wp-content\\\/uploads\\\/2012\\\/06\\\/TPT_LOGO.jpg\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2013\\\/01\\\/08\\\/huisstijl-tandartspraktijk-tivoli-ilovit\\\/#articleImage\"},\"datePublished\":\"2013-01-08T11:15:31+01:00\",\"dateModified\":\"2013-01-08T11:15:31+01:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2013\\\/01\\\/08\\\/huisstijl-tandartspraktijk-tivoli-ilovit\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2013\\\/01\\\/08\\\/huisstijl-tandartspraktijk-tivoli-ilovit\\\/#webpage\"},\"articleSection\":\"Drukwerk, Huisstijlen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2013\\\/01\\\/08\\\/huisstijl-tandartspraktijk-tivoli-ilovit\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/judithsanders.nl\\\/website\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/category\\\/drukwerk\\\/#listItem\",\"name\":\"Drukwerk\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/category\\\/drukwerk\\\/#listItem\",\"position\":2,\"name\":\"Drukwerk\",\"item\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/category\\\/drukwerk\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2013\\\/01\\\/08\\\/huisstijl-tandartspraktijk-tivoli-ilovit\\\/#listItem\",\"name\":\"Huisstijl Tandartspraktijk Tivoli \\\/ iloviT\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2013\\\/01\\\/08\\\/huisstijl-tandartspraktijk-tivoli-ilovit\\\/#listItem\",\"position\":3,\"name\":\"Huisstijl Tandartspraktijk Tivoli \\\/ iloviT\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/category\\\/drukwerk\\\/#listItem\",\"name\":\"Drukwerk\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#organization\",\"name\":\"Judith Sanders MultiMedia & e-Learning\",\"description\":\"Freelance e-Learning designer and developer Totaaloplossing e-Learning Naast mijn design competenties lever ik diverse nevendiensten die samen een allround servicepakket opleveren om alle e-Learning en andere diverse digitale projecten perfect op te kunnen leveren, al dan niet in partnership. Design wordt als \\u00e9\\u00e9n van de hoofddisciplines aangeboden, waarbij het eindresultaat gebruiksvriendelijk is en professioneel oogt. Het is intu\\u00eftief en spreekt de beoogde doelgroep aan. Technisch ben ik competent en is er weinig wat niet kan in mijn beleving. Mocht het nodig zijn dan kan ik altijd nog iemand uit mijn netwerk inschakelen om het project extra kracht bij te zetten. Mijn toegevoegde waarde is luisteren naar uw wensen en deze optimaal vertalen naar het product van uw keuze.\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/\",\"telephone\":\"+31652460068\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo_judithsanders_grijsverloop.png\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2013\\\/01\\\/08\\\/huisstijl-tandartspraktijk-tivoli-ilovit\\\/#organizationLogo\",\"width\":1039,\"height\":1060},\"image\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2013\\\/01\\\/08\\\/huisstijl-tandartspraktijk-tivoli-ilovit\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/judithsanders\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/#author\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2013\\\/01\\\/08\\\/huisstijl-tandartspraktijk-tivoli-ilovit\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fca062c59add9c0becf05d336fedb615de736cc5a007bc2c39f46bb848991a1b?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2013\\\/01\\\/08\\\/huisstijl-tandartspraktijk-tivoli-ilovit\\\/#webpage\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2013\\\/01\\\/08\\\/huisstijl-tandartspraktijk-tivoli-ilovit\\\/\",\"name\":\"Huisstijl Tandartspraktijk Tivoli \\\/ iloviT - Judith Sanders MultiMedia & e-Learning\",\"description\":\"Voor Tandartspraktijk Tivoli ben ik begonnen met het ontwikkelen van een website in combinatie met het redesign van het logo. Nadat de website is gelanceerd zijn ook diverse huisstijlelementen onder handen genomen waaronder de visitekaartjes, het briefpapier, een variatie in enveloppen, with compliments kaarten en 3 soorten afsprakenkaartjes. De website kunt u ook hier binnen\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2013\\\/01\\\/08\\\/huisstijl-tandartspraktijk-tivoli-ilovit\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/#author\"},\"datePublished\":\"2013-01-08T11:15:31+01:00\",\"dateModified\":\"2013-01-08T11:15:31+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#website\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/\",\"name\":\"Judith Sanders MultiMedia & e-Learning\",\"description\":\"Freelance e-Learning designer and developer\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Huisstijl Tandartspraktijk Tivoli \/ iloviT - Judith Sanders MultiMedia & e-Learning","description":"Voor Tandartspraktijk Tivoli ben ik begonnen met het ontwikkelen van een website in combinatie met het redesign van het logo. Nadat de website is gelanceerd zijn ook diverse huisstijlelementen onder handen genomen waaronder de visitekaartjes, het briefpapier, een variatie in enveloppen, with compliments kaarten en 3 soorten afsprakenkaartjes. De website kunt u ook hier binnen","canonical_url":"https:\/\/judithsanders.nl\/website\/index.php\/2013\/01\/08\/huisstijl-tandartspraktijk-tivoli-ilovit\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"WO6NTrPSlDMSbKVdm2D1-_LuA9xh_r0XoPxxl90knfQ","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2013\/01\/08\/huisstijl-tandartspraktijk-tivoli-ilovit\/#blogposting","name":"Huisstijl Tandartspraktijk Tivoli \/ iloviT - Judith Sanders MultiMedia & e-Learning","headline":"Huisstijl Tandartspraktijk Tivoli \/ iloviT","author":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/#author"},"publisher":{"@id":"https:\/\/judithsanders.nl\/website\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2012\/06\/TPT_LOGO.jpg","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2013\/01\/08\/huisstijl-tandartspraktijk-tivoli-ilovit\/#articleImage"},"datePublished":"2013-01-08T11:15:31+01:00","dateModified":"2013-01-08T11:15:31+01:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/2013\/01\/08\/huisstijl-tandartspraktijk-tivoli-ilovit\/#webpage"},"isPartOf":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/2013\/01\/08\/huisstijl-tandartspraktijk-tivoli-ilovit\/#webpage"},"articleSection":"Drukwerk, Huisstijlen"},{"@type":"BreadcrumbList","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2013\/01\/08\/huisstijl-tandartspraktijk-tivoli-ilovit\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website#listItem","position":1,"name":"Home","item":"https:\/\/judithsanders.nl\/website","nextItem":{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/category\/drukwerk\/#listItem","name":"Drukwerk"}},{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/category\/drukwerk\/#listItem","position":2,"name":"Drukwerk","item":"https:\/\/judithsanders.nl\/website\/index.php\/category\/drukwerk\/","nextItem":{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2013\/01\/08\/huisstijl-tandartspraktijk-tivoli-ilovit\/#listItem","name":"Huisstijl Tandartspraktijk Tivoli \/ iloviT"},"previousItem":{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2013\/01\/08\/huisstijl-tandartspraktijk-tivoli-ilovit\/#listItem","position":3,"name":"Huisstijl Tandartspraktijk Tivoli \/ iloviT","previousItem":{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/category\/drukwerk\/#listItem","name":"Drukwerk"}}]},{"@type":"Organization","@id":"https:\/\/judithsanders.nl\/website\/#organization","name":"Judith Sanders MultiMedia & e-Learning","description":"Freelance e-Learning designer and developer Totaaloplossing e-Learning Naast mijn design competenties lever ik diverse nevendiensten die samen een allround servicepakket opleveren om alle e-Learning en andere diverse digitale projecten perfect op te kunnen leveren, al dan niet in partnership. Design wordt als \u00e9\u00e9n van de hoofddisciplines aangeboden, waarbij het eindresultaat gebruiksvriendelijk is en professioneel oogt. Het is intu\u00eftief en spreekt de beoogde doelgroep aan. Technisch ben ik competent en is er weinig wat niet kan in mijn beleving. Mocht het nodig zijn dan kan ik altijd nog iemand uit mijn netwerk inschakelen om het project extra kracht bij te zetten. Mijn toegevoegde waarde is luisteren naar uw wensen en deze optimaal vertalen naar het product van uw keuze.","url":"https:\/\/judithsanders.nl\/website\/","telephone":"+31652460068","logo":{"@type":"ImageObject","url":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2013\/01\/08\/huisstijl-tandartspraktijk-tivoli-ilovit\/#organizationLogo","width":1039,"height":1060},"image":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/2013\/01\/08\/huisstijl-tandartspraktijk-tivoli-ilovit\/#organizationLogo"},"sameAs":["https:\/\/www.linkedin.com\/in\/judithsanders\/"]},{"@type":"Person","@id":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/#author","url":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2013\/01\/08\/huisstijl-tandartspraktijk-tivoli-ilovit\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/fca062c59add9c0becf05d336fedb615de736cc5a007bc2c39f46bb848991a1b?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2013\/01\/08\/huisstijl-tandartspraktijk-tivoli-ilovit\/#webpage","url":"https:\/\/judithsanders.nl\/website\/index.php\/2013\/01\/08\/huisstijl-tandartspraktijk-tivoli-ilovit\/","name":"Huisstijl Tandartspraktijk Tivoli \/ iloviT - Judith Sanders MultiMedia & e-Learning","description":"Voor Tandartspraktijk Tivoli ben ik begonnen met het ontwikkelen van een website in combinatie met het redesign van het logo. Nadat de website is gelanceerd zijn ook diverse huisstijlelementen onder handen genomen waaronder de visitekaartjes, het briefpapier, een variatie in enveloppen, with compliments kaarten en 3 soorten afsprakenkaartjes. De website kunt u ook hier binnen","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/judithsanders.nl\/website\/#website"},"breadcrumb":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/2013\/01\/08\/huisstijl-tandartspraktijk-tivoli-ilovit\/#breadcrumblist"},"author":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/#author"},"creator":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/#author"},"datePublished":"2013-01-08T11:15:31+01:00","dateModified":"2013-01-08T11:15:31+01:00"},{"@type":"WebSite","@id":"https:\/\/judithsanders.nl\/website\/#website","url":"https:\/\/judithsanders.nl\/website\/","name":"Judith Sanders MultiMedia & e-Learning","description":"Freelance e-Learning designer and developer","inLanguage":"en-US","publisher":{"@id":"https:\/\/judithsanders.nl\/website\/#organization"}}]},"og:locale":"en_US","og:site_name":"Judith Sanders MultiMedia &amp; e-Learning - Freelance e-Learning designer and developer","og:type":"article","og:title":"Huisstijl Tandartspraktijk Tivoli \/ iloviT - Judith Sanders MultiMedia &amp; e-Learning","og:description":"Voor Tandartspraktijk Tivoli ben ik begonnen met het ontwikkelen van een website in combinatie met het redesign van het logo. Nadat de website is gelanceerd zijn ook diverse huisstijlelementen onder handen genomen waaronder de visitekaartjes, het briefpapier, een variatie in enveloppen, with compliments kaarten en 3 soorten afsprakenkaartjes. De website kunt u ook hier binnen","og:url":"https:\/\/judithsanders.nl\/website\/index.php\/2013\/01\/08\/huisstijl-tandartspraktijk-tivoli-ilovit\/","og:image":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png","og:image:secure_url":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png","og:image:width":1039,"og:image:height":1060,"article:published_time":"2013-01-08T10:15:31+00:00","article:modified_time":"2013-01-08T10:15:31+00:00","twitter:card":"summary_large_image","twitter:title":"Huisstijl Tandartspraktijk Tivoli \/ iloviT - Judith Sanders MultiMedia &amp; e-Learning","twitter:description":"Voor Tandartspraktijk Tivoli ben ik begonnen met het ontwikkelen van een website in combinatie met het redesign van het logo. Nadat de website is gelanceerd zijn ook diverse huisstijlelementen onder handen genomen waaronder de visitekaartjes, het briefpapier, een variatie in enveloppen, with compliments kaarten en 3 soorten afsprakenkaartjes. De website kunt u ook hier binnen","twitter:image":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png"},"aioseo_meta_data":{"post_id":"1650","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-01-24 00:18:02","updated":"2025-06-04 16:48:05","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/judithsanders.nl\/website\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/judithsanders.nl\/website\/index.php\/category\/drukwerk\/\" title=\"Drukwerk\">Drukwerk<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tHuisstijl Tandartspraktijk Tivoli \/ iloviT\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/judithsanders.nl\/website"},{"label":"Drukwerk","link":"https:\/\/judithsanders.nl\/website\/index.php\/category\/drukwerk\/"},{"label":"Huisstijl Tandartspraktijk Tivoli \/ iloviT","link":"https:\/\/judithsanders.nl\/website\/index.php\/2013\/01\/08\/huisstijl-tandartspraktijk-tivoli-ilovit\/"}],"_links":{"self":[{"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/posts\/1650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/comments?post=1650"}],"version-history":[{"count":0,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/posts\/1650\/revisions"}],"wp:attachment":[{"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/media?parent=1650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/categories?post=1650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/tags?post=1650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}