{"id":2550,"date":"2014-12-03T14:30:43","date_gmt":"2014-12-03T13:30:43","guid":{"rendered":"http:\/\/www.judithsanders.nl\/site\/?p=2550"},"modified":"2014-12-03T14:30:43","modified_gmt":"2014-12-03T13:30:43","slug":"e-learning-philips-healthcare-2","status":"publish","type":"post","link":"https:\/\/judithsanders.nl\/website\/index.php\/2014\/12\/03\/e-learning-philips-healthcare-2\/","title":{"rendered":"E-Learning Philips Healthcare HandHeld Diagnostics"},"content":{"rendered":"<p>Voor Philips Healthcare HandHeld Diagnostics heb ik een klein deel uit mogen maken van de launch van een nieuw innovatief product: de Minicare I-20. Ik heb een eLearning tutorial gemaakt voor dit nieuwe apparaat.  Een arts of verpleger kan met behulp van de Minicare ter plekke vaststellen of een hartaanval dreigt bij de pati\u00ebnt van wie hij zojuist een druppel bloed afgenomen heeft. De Minicare analyseert het bloed, dat uit een vinger wordt geprikt, in enkele minuten.<\/p>\n<p>Deze eLearning omvat de basis functionaliteit wat door verpleegkundigen in een ziekenhuis geleerd moet worden om het apparaat te kunnen gebruiken. Dit project omvat buiten software simulaties ook videomateriaal. De eLearning is opgeleverd in het Engels met voiceover, inclusief de on-screen vertaalversies in het Nederlands, Duits en Frans.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2014\/12\/PhilipsMinicare.jpg\" alt=\"Philips eLearning Minicare\" width=\"532\" height=\"317\" \/><\/p>\n<p>Het is een lineaire eLearning waarbij gebruikers stapsgewijs door het leerproces geleid worden. Dit is zo opgezet dat bij afronding van ieder hoofdstuk pas het volgende hoofdstuk in het menu zichtbaar wordt. Hierdoor weten we zeker dat mensen de informatie op de juiste manier tot zich nemen en voorkomen we dat gebruikers geen informatie voor ogen krijgen die ze pas begrijpen als ze andere stukken gezien hebben. Ook is het zo overzichtelijk waar ze gebleven zijn in de training en kan er gecertificeerd worden bij het afronden van het laatste hoofdstuk.<\/p>\n<ul>\n<li>Adobe Photoshop<\/li>\n<li>Adobe Premiere<\/li>\n<li>Articulate Storyline<\/li>\n<\/ul>\n<p><em>Ontwerp &#038; ontwikkeling 2014. Vervolg project &#8211; aanvullingen in 2015.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voor Philips Healthcare HandHeld Diagnostics heb ik een klein deel uit mogen maken van de launch van een nieuw innovatief&#8230; <\/p>\n<div class=\"art-el-more\"><a href=\"https:\/\/judithsanders.nl\/website\/index.php\/2014\/12\/03\/e-learning-philips-healthcare-2\/\" class=\"art-link art-color-link art-w-chevron\">Read more<\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[45],"tags":[],"class_list":["post-2550","post","type-post","status-publish","format-standard","hentry","category-e-learning"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Voor Philips Healthcare HandHeld Diagnostics heb ik een klein deel uit mogen maken van de launch van een nieuw innovatief product: de Minicare I-20. Ik heb een eLearning tutorial gemaakt voor dit nieuwe apparaat. Een arts of verpleger kan met behulp van de Minicare ter plekke vaststellen of een hartaanval dreigt bij de pati\u00ebnt van\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"WO6NTrPSlDMSbKVdm2D1-_LuA9xh_r0XoPxxl90knfQ\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/judithsanders.nl\/website\/index.php\/2014\/12\/03\/e-learning-philips-healthcare-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Judith Sanders MultiMedia &amp; e-Learning - Freelance e-Learning designer and developer\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"E-Learning Philips Healthcare HandHeld Diagnostics - Judith Sanders MultiMedia &amp; e-Learning\" \/>\n\t\t<meta property=\"og:description\" content=\"Voor Philips Healthcare HandHeld Diagnostics heb ik een klein deel uit mogen maken van de launch van een nieuw innovatief product: de Minicare I-20. Ik heb een eLearning tutorial gemaakt voor dit nieuwe apparaat. Een arts of verpleger kan met behulp van de Minicare ter plekke vaststellen of een hartaanval dreigt bij de pati\u00ebnt van\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/judithsanders.nl\/website\/index.php\/2014\/12\/03\/e-learning-philips-healthcare-2\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1039\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1060\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2014-12-03T13:30:43+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2014-12-03T13:30:43+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"E-Learning Philips Healthcare HandHeld Diagnostics - Judith Sanders MultiMedia &amp; e-Learning\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Voor Philips Healthcare HandHeld Diagnostics heb ik een klein deel uit mogen maken van de launch van een nieuw innovatief product: de Minicare I-20. Ik heb een eLearning tutorial gemaakt voor dit nieuwe apparaat. Een arts of verpleger kan met behulp van de Minicare ter plekke vaststellen of een hartaanval dreigt bij de pati\u00ebnt van\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2014\\\/12\\\/03\\\/e-learning-philips-healthcare-2\\\/#blogposting\",\"name\":\"E-Learning Philips Healthcare HandHeld Diagnostics - Judith Sanders MultiMedia & e-Learning\",\"headline\":\"E-Learning Philips Healthcare HandHeld Diagnostics\",\"author\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.judithsanders.nl\\\/site\\\/wp-content\\\/uploads\\\/2014\\\/12\\\/PhilipsMinicare.jpg\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2014\\\/12\\\/03\\\/e-learning-philips-healthcare-2\\\/#articleImage\"},\"datePublished\":\"2014-12-03T14:30:43+01:00\",\"dateModified\":\"2014-12-03T14:30:43+01:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2014\\\/12\\\/03\\\/e-learning-philips-healthcare-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2014\\\/12\\\/03\\\/e-learning-philips-healthcare-2\\\/#webpage\"},\"articleSection\":\"E-Learning\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2014\\\/12\\\/03\\\/e-learning-philips-healthcare-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/judithsanders.nl\\\/website\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/category\\\/e-learning\\\/#listItem\",\"name\":\"E-Learning\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/category\\\/e-learning\\\/#listItem\",\"position\":2,\"name\":\"E-Learning\",\"item\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/category\\\/e-learning\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2014\\\/12\\\/03\\\/e-learning-philips-healthcare-2\\\/#listItem\",\"name\":\"E-Learning Philips Healthcare HandHeld Diagnostics\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2014\\\/12\\\/03\\\/e-learning-philips-healthcare-2\\\/#listItem\",\"position\":3,\"name\":\"E-Learning Philips Healthcare HandHeld Diagnostics\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/category\\\/e-learning\\\/#listItem\",\"name\":\"E-Learning\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#organization\",\"name\":\"Judith Sanders MultiMedia & e-Learning\",\"description\":\"Freelance e-Learning designer and developer Totaaloplossing e-Learning Naast mijn design competenties lever ik diverse nevendiensten die samen een allround servicepakket opleveren om alle e-Learning en andere diverse digitale projecten perfect op te kunnen leveren, al dan niet in partnership. Design wordt als \\u00e9\\u00e9n van de hoofddisciplines aangeboden, waarbij het eindresultaat gebruiksvriendelijk is en professioneel oogt. Het is intu\\u00eftief en spreekt de beoogde doelgroep aan. Technisch ben ik competent en is er weinig wat niet kan in mijn beleving. Mocht het nodig zijn dan kan ik altijd nog iemand uit mijn netwerk inschakelen om het project extra kracht bij te zetten. Mijn toegevoegde waarde is luisteren naar uw wensen en deze optimaal vertalen naar het product van uw keuze.\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/\",\"telephone\":\"+31652460068\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo_judithsanders_grijsverloop.png\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2014\\\/12\\\/03\\\/e-learning-philips-healthcare-2\\\/#organizationLogo\",\"width\":1039,\"height\":1060},\"image\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2014\\\/12\\\/03\\\/e-learning-philips-healthcare-2\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/judithsanders\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/#author\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2014\\\/12\\\/03\\\/e-learning-philips-healthcare-2\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fca062c59add9c0becf05d336fedb615de736cc5a007bc2c39f46bb848991a1b?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2014\\\/12\\\/03\\\/e-learning-philips-healthcare-2\\\/#webpage\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2014\\\/12\\\/03\\\/e-learning-philips-healthcare-2\\\/\",\"name\":\"E-Learning Philips Healthcare HandHeld Diagnostics - Judith Sanders MultiMedia & e-Learning\",\"description\":\"Voor Philips Healthcare HandHeld Diagnostics heb ik een klein deel uit mogen maken van de launch van een nieuw innovatief product: de Minicare I-20. Ik heb een eLearning tutorial gemaakt voor dit nieuwe apparaat. Een arts of verpleger kan met behulp van de Minicare ter plekke vaststellen of een hartaanval dreigt bij de pati\\u00ebnt van\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2014\\\/12\\\/03\\\/e-learning-philips-healthcare-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/#author\"},\"datePublished\":\"2014-12-03T14:30:43+01:00\",\"dateModified\":\"2014-12-03T14:30:43+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#website\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/\",\"name\":\"Judith Sanders MultiMedia & e-Learning\",\"description\":\"Freelance e-Learning designer and developer\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"E-Learning Philips Healthcare HandHeld Diagnostics - Judith Sanders MultiMedia & e-Learning","description":"Voor Philips Healthcare HandHeld Diagnostics heb ik een klein deel uit mogen maken van de launch van een nieuw innovatief product: de Minicare I-20. Ik heb een eLearning tutorial gemaakt voor dit nieuwe apparaat. Een arts of verpleger kan met behulp van de Minicare ter plekke vaststellen of een hartaanval dreigt bij de pati\u00ebnt van","canonical_url":"https:\/\/judithsanders.nl\/website\/index.php\/2014\/12\/03\/e-learning-philips-healthcare-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"WO6NTrPSlDMSbKVdm2D1-_LuA9xh_r0XoPxxl90knfQ","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2014\/12\/03\/e-learning-philips-healthcare-2\/#blogposting","name":"E-Learning Philips Healthcare HandHeld Diagnostics - Judith Sanders MultiMedia & e-Learning","headline":"E-Learning Philips Healthcare HandHeld Diagnostics","author":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/#author"},"publisher":{"@id":"https:\/\/judithsanders.nl\/website\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2014\/12\/PhilipsMinicare.jpg","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2014\/12\/03\/e-learning-philips-healthcare-2\/#articleImage"},"datePublished":"2014-12-03T14:30:43+01:00","dateModified":"2014-12-03T14:30:43+01:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/2014\/12\/03\/e-learning-philips-healthcare-2\/#webpage"},"isPartOf":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/2014\/12\/03\/e-learning-philips-healthcare-2\/#webpage"},"articleSection":"E-Learning"},{"@type":"BreadcrumbList","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2014\/12\/03\/e-learning-philips-healthcare-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website#listItem","position":1,"name":"Home","item":"https:\/\/judithsanders.nl\/website","nextItem":{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/category\/e-learning\/#listItem","name":"E-Learning"}},{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/category\/e-learning\/#listItem","position":2,"name":"E-Learning","item":"https:\/\/judithsanders.nl\/website\/index.php\/category\/e-learning\/","nextItem":{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2014\/12\/03\/e-learning-philips-healthcare-2\/#listItem","name":"E-Learning Philips Healthcare HandHeld Diagnostics"},"previousItem":{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2014\/12\/03\/e-learning-philips-healthcare-2\/#listItem","position":3,"name":"E-Learning Philips Healthcare HandHeld Diagnostics","previousItem":{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/category\/e-learning\/#listItem","name":"E-Learning"}}]},{"@type":"Organization","@id":"https:\/\/judithsanders.nl\/website\/#organization","name":"Judith Sanders MultiMedia & e-Learning","description":"Freelance e-Learning designer and developer Totaaloplossing e-Learning Naast mijn design competenties lever ik diverse nevendiensten die samen een allround servicepakket opleveren om alle e-Learning en andere diverse digitale projecten perfect op te kunnen leveren, al dan niet in partnership. Design wordt als \u00e9\u00e9n van de hoofddisciplines aangeboden, waarbij het eindresultaat gebruiksvriendelijk is en professioneel oogt. Het is intu\u00eftief en spreekt de beoogde doelgroep aan. Technisch ben ik competent en is er weinig wat niet kan in mijn beleving. Mocht het nodig zijn dan kan ik altijd nog iemand uit mijn netwerk inschakelen om het project extra kracht bij te zetten. Mijn toegevoegde waarde is luisteren naar uw wensen en deze optimaal vertalen naar het product van uw keuze.","url":"https:\/\/judithsanders.nl\/website\/","telephone":"+31652460068","logo":{"@type":"ImageObject","url":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2014\/12\/03\/e-learning-philips-healthcare-2\/#organizationLogo","width":1039,"height":1060},"image":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/2014\/12\/03\/e-learning-philips-healthcare-2\/#organizationLogo"},"sameAs":["https:\/\/www.linkedin.com\/in\/judithsanders\/"]},{"@type":"Person","@id":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/#author","url":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2014\/12\/03\/e-learning-philips-healthcare-2\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/fca062c59add9c0becf05d336fedb615de736cc5a007bc2c39f46bb848991a1b?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2014\/12\/03\/e-learning-philips-healthcare-2\/#webpage","url":"https:\/\/judithsanders.nl\/website\/index.php\/2014\/12\/03\/e-learning-philips-healthcare-2\/","name":"E-Learning Philips Healthcare HandHeld Diagnostics - Judith Sanders MultiMedia & e-Learning","description":"Voor Philips Healthcare HandHeld Diagnostics heb ik een klein deel uit mogen maken van de launch van een nieuw innovatief product: de Minicare I-20. Ik heb een eLearning tutorial gemaakt voor dit nieuwe apparaat. Een arts of verpleger kan met behulp van de Minicare ter plekke vaststellen of een hartaanval dreigt bij de pati\u00ebnt van","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/judithsanders.nl\/website\/#website"},"breadcrumb":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/2014\/12\/03\/e-learning-philips-healthcare-2\/#breadcrumblist"},"author":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/#author"},"creator":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/#author"},"datePublished":"2014-12-03T14:30:43+01:00","dateModified":"2014-12-03T14:30:43+01:00"},{"@type":"WebSite","@id":"https:\/\/judithsanders.nl\/website\/#website","url":"https:\/\/judithsanders.nl\/website\/","name":"Judith Sanders MultiMedia & e-Learning","description":"Freelance e-Learning designer and developer","inLanguage":"en-US","publisher":{"@id":"https:\/\/judithsanders.nl\/website\/#organization"}}]},"og:locale":"en_US","og:site_name":"Judith Sanders MultiMedia &amp; e-Learning - Freelance e-Learning designer and developer","og:type":"article","og:title":"E-Learning Philips Healthcare HandHeld Diagnostics - Judith Sanders MultiMedia &amp; e-Learning","og:description":"Voor Philips Healthcare HandHeld Diagnostics heb ik een klein deel uit mogen maken van de launch van een nieuw innovatief product: de Minicare I-20. Ik heb een eLearning tutorial gemaakt voor dit nieuwe apparaat. Een arts of verpleger kan met behulp van de Minicare ter plekke vaststellen of een hartaanval dreigt bij de pati\u00ebnt van","og:url":"https:\/\/judithsanders.nl\/website\/index.php\/2014\/12\/03\/e-learning-philips-healthcare-2\/","og:image":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png","og:image:secure_url":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png","og:image:width":1039,"og:image:height":1060,"article:published_time":"2014-12-03T13:30:43+00:00","article:modified_time":"2014-12-03T13:30:43+00:00","twitter:card":"summary_large_image","twitter:title":"E-Learning Philips Healthcare HandHeld Diagnostics - Judith Sanders MultiMedia &amp; e-Learning","twitter:description":"Voor Philips Healthcare HandHeld Diagnostics heb ik een klein deel uit mogen maken van de launch van een nieuw innovatief product: de Minicare I-20. Ik heb een eLearning tutorial gemaakt voor dit nieuwe apparaat. Een arts of verpleger kan met behulp van de Minicare ter plekke vaststellen of een hartaanval dreigt bij de pati\u00ebnt van","twitter:image":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png"},"aioseo_meta_data":{"post_id":"2550","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-01-24 01:18:02","updated":"2025-06-04 17:48:05","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/judithsanders.nl\/website\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/judithsanders.nl\/website\/index.php\/category\/e-learning\/\" title=\"E-Learning\">E-Learning<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tE-Learning Philips Healthcare HandHeld Diagnostics\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/judithsanders.nl\/website"},{"label":"E-Learning","link":"https:\/\/judithsanders.nl\/website\/index.php\/category\/e-learning\/"},{"label":"E-Learning Philips Healthcare HandHeld Diagnostics","link":"https:\/\/judithsanders.nl\/website\/index.php\/2014\/12\/03\/e-learning-philips-healthcare-2\/"}],"_links":{"self":[{"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/posts\/2550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/comments?post=2550"}],"version-history":[{"count":0,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/posts\/2550\/revisions"}],"wp:attachment":[{"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/media?parent=2550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/categories?post=2550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/tags?post=2550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}