{"id":3344,"date":"2017-08-01T18:42:12","date_gmt":"2017-08-01T17:42:12","guid":{"rendered":"http:\/\/www.judithsanders.nl\/site\/?p=3344"},"modified":"2024-04-24T15:16:36","modified_gmt":"2024-04-24T14:16:36","slug":"e-learning-template-skillsonline-bohn-stafleu-van-loghum","status":"publish","type":"post","link":"https:\/\/judithsanders.nl\/website\/index.php\/2017\/08\/01\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\/","title":{"rendered":"E-Learning template Skills Online BSL"},"content":{"rendered":"<p>In opdracht van Bohn Stafleu van Loghum (BSL) mocht ik van scratch een geavanceerde en complete Articulate Storyline template maken voor het BSL leerplatform &#8216;Skills Online&#8217;.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2019\/06\/BSL_logo_RGB_LR-2.jpg\" alt=\"Bohn Stafleu van Loghum Logo\" width=\"300\" height=\"95\" \/><\/p>\n<p>Als uitgangspunt kreeg ik de inhoud van een nieuwe module (onderwerp &#8216;Injecteren&#8217;) in combinatie met de nieuwe e-Learning visie. Het design was vrij, er waren geen huisstijlregels om me aan te confirmeren. Het resultaat is een zeer uitgebreide ontworpen interface die bestaat uit een 30-tal verschillende layouts en ingevulde interacties. Dit met verschillende leerpaden voor verschillende niveaus inclusief geavanceerde toetsing met custom feedback. Met gebruik van deze template kunnen vergevorderde Storyline ontwikkelaars zelf eenduidige en kwalitatieve Skills Online modules maken waarbij de gebruiker op een aantrekkelijke, duidelijke en gemakkelijke wijze de informatie in zich op kan nemen.<\/p>\n<p>Deze template is veelvuldig ingezet bij het ontwikkelen van nieuwe modules.<\/p>\n<ul>\n<li>Adobe Photoshop<\/li>\n<li>Articulate Storyline<\/li>\n<\/ul>\n<p><em>Design &amp; Ontwikkeling.<\/em><\/p>\n<hr \/>\n<p><strong>Achtergrond informatie<\/strong><br \/>\nBohn Stafleu van Loghum biedt als uitgeverij betrouwbare, Nederlandstalige vakinformatie, educatieve uitgaven en diensten voor opleiding en beroepsuitoefening. Daarbij richten zij zich op zowel studenten en professionals als bestuurders in zorg en welzijn.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2017\/08\/skillsonline1_532.jpg\" alt=\"skillsonline1_532\" width=\"290\" height=\"167\" \/>\u00a0<img decoding=\"async\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2017\/08\/skillsonline3_532.jpg\" alt=\"skillsonline3_532\" width=\"290\" height=\"167\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2017\/08\/skillsonline4_532.jpg\" alt=\"skillsonline4_532\" width=\"290\" height=\"167\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2017\/08\/skillsonline8_532.jpg\" alt=\"skillsonline8_532\" width=\"290\" height=\"167\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2017\/08\/skillsonline5.png\" alt=\"skillsonline5\" width=\"290\" height=\"167\" \/>\u00a0<img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2017\/08\/skillsonline7.png\" alt=\"skillsonline7\" width=\"290\" height=\"167\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In opdracht van Bohn Stafleu van Loghum (BSL) mocht ik van scratch een geavanceerde en complete Articulate Storyline template maken&#8230; <\/p>\n<div class=\"art-el-more\"><a href=\"https:\/\/judithsanders.nl\/website\/index.php\/2017\/08\/01\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\/\" class=\"art-link art-color-link art-w-chevron\">Read more<\/a><\/div>\n","protected":false},"author":1,"featured_media":5216,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[45],"tags":[],"class_list":["post-3344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-e-learning"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"In opdracht van Bohn Stafleu van Loghum (BSL) mocht ik van scratch een geavanceerde en complete Articulate Storyline template maken voor het BSL leerplatform &#039;Skills Online&#039;. Als uitgangspunt kreeg ik de inhoud van een nieuwe module (onderwerp &#039;Injecteren&#039;) in combinatie met de nieuwe e-Learning visie. Het design was vrij, er waren geen huisstijlregels om me\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"WO6NTrPSlDMSbKVdm2D1-_LuA9xh_r0XoPxxl90knfQ\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/judithsanders.nl\/website\/index.php\/2017\/08\/01\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Judith Sanders MultiMedia &amp; e-Learning - Freelance e-Learning designer and developer\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"E-Learning template Skills Online BSL - Judith Sanders MultiMedia &amp; e-Learning\" \/>\n\t\t<meta property=\"og:description\" content=\"In opdracht van Bohn Stafleu van Loghum (BSL) mocht ik van scratch een geavanceerde en complete Articulate Storyline template maken voor het BSL leerplatform &#039;Skills Online&#039;. Als uitgangspunt kreeg ik de inhoud van een nieuwe module (onderwerp &#039;Injecteren&#039;) in combinatie met de nieuwe e-Learning visie. Het design was vrij, er waren geen huisstijlregels om me\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/judithsanders.nl\/website\/index.php\/2017\/08\/01\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1039\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1060\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2017-08-01T17:42:12+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-04-24T14:16:36+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"E-Learning template Skills Online BSL - Judith Sanders MultiMedia &amp; e-Learning\" \/>\n\t\t<meta name=\"twitter:description\" content=\"In opdracht van Bohn Stafleu van Loghum (BSL) mocht ik van scratch een geavanceerde en complete Articulate Storyline template maken voor het BSL leerplatform &#039;Skills Online&#039;. Als uitgangspunt kreeg ik de inhoud van een nieuwe module (onderwerp &#039;Injecteren&#039;) in combinatie met de nieuwe e-Learning visie. Het design was vrij, er waren geen huisstijlregels om me\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2017\\\/08\\\/01\\\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\\\/#blogposting\",\"name\":\"E-Learning template Skills Online BSL - Judith Sanders MultiMedia & e-Learning\",\"headline\":\"E-Learning template Skills Online BSL\",\"author\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/featured_BSL_templateSkillsOnline.jpg\",\"width\":1000,\"height\":600},\"datePublished\":\"2017-08-01T18:42:12+01:00\",\"dateModified\":\"2024-04-24T15:16:36+01:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2017\\\/08\\\/01\\\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2017\\\/08\\\/01\\\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\\\/#webpage\"},\"articleSection\":\"E-Learning\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2017\\\/08\\\/01\\\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/judithsanders.nl\\\/website\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/category\\\/e-learning\\\/#listItem\",\"name\":\"E-Learning\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/category\\\/e-learning\\\/#listItem\",\"position\":2,\"name\":\"E-Learning\",\"item\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/category\\\/e-learning\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2017\\\/08\\\/01\\\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\\\/#listItem\",\"name\":\"E-Learning template Skills Online BSL\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2017\\\/08\\\/01\\\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\\\/#listItem\",\"position\":3,\"name\":\"E-Learning template Skills Online BSL\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/category\\\/e-learning\\\/#listItem\",\"name\":\"E-Learning\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#organization\",\"name\":\"Judith Sanders MultiMedia & e-Learning\",\"description\":\"Freelance e-Learning designer and developer Totaaloplossing e-Learning Naast mijn design competenties lever ik diverse nevendiensten die samen een allround servicepakket opleveren om alle e-Learning en andere diverse digitale projecten perfect op te kunnen leveren, al dan niet in partnership. Design wordt als \\u00e9\\u00e9n van de hoofddisciplines aangeboden, waarbij het eindresultaat gebruiksvriendelijk is en professioneel oogt. Het is intu\\u00eftief en spreekt de beoogde doelgroep aan. Technisch ben ik competent en is er weinig wat niet kan in mijn beleving. Mocht het nodig zijn dan kan ik altijd nog iemand uit mijn netwerk inschakelen om het project extra kracht bij te zetten. Mijn toegevoegde waarde is luisteren naar uw wensen en deze optimaal vertalen naar het product van uw keuze.\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/\",\"telephone\":\"+31652460068\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo_judithsanders_grijsverloop.png\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2017\\\/08\\\/01\\\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\\\/#organizationLogo\",\"width\":1039,\"height\":1060},\"image\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2017\\\/08\\\/01\\\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/judithsanders\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/#author\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2017\\\/08\\\/01\\\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fca062c59add9c0becf05d336fedb615de736cc5a007bc2c39f46bb848991a1b?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2017\\\/08\\\/01\\\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\\\/#webpage\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2017\\\/08\\\/01\\\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\\\/\",\"name\":\"E-Learning template Skills Online BSL - Judith Sanders MultiMedia & e-Learning\",\"description\":\"In opdracht van Bohn Stafleu van Loghum (BSL) mocht ik van scratch een geavanceerde en complete Articulate Storyline template maken voor het BSL leerplatform 'Skills Online'. Als uitgangspunt kreeg ik de inhoud van een nieuwe module (onderwerp 'Injecteren') in combinatie met de nieuwe e-Learning visie. Het design was vrij, er waren geen huisstijlregels om me\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2017\\\/08\\\/01\\\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/featured_BSL_templateSkillsOnline.jpg\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2017\\\/08\\\/01\\\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\\\/#mainImage\",\"width\":1000,\"height\":600},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2017\\\/08\\\/01\\\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\\\/#mainImage\"},\"datePublished\":\"2017-08-01T18:42:12+01:00\",\"dateModified\":\"2024-04-24T15:16:36+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#website\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/\",\"name\":\"Judith Sanders MultiMedia & e-Learning\",\"description\":\"Freelance e-Learning designer and developer\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"E-Learning template Skills Online BSL - Judith Sanders MultiMedia & e-Learning","description":"In opdracht van Bohn Stafleu van Loghum (BSL) mocht ik van scratch een geavanceerde en complete Articulate Storyline template maken voor het BSL leerplatform 'Skills Online'. Als uitgangspunt kreeg ik de inhoud van een nieuwe module (onderwerp 'Injecteren') in combinatie met de nieuwe e-Learning visie. Het design was vrij, er waren geen huisstijlregels om me","canonical_url":"https:\/\/judithsanders.nl\/website\/index.php\/2017\/08\/01\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"WO6NTrPSlDMSbKVdm2D1-_LuA9xh_r0XoPxxl90knfQ","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2017\/08\/01\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\/#blogposting","name":"E-Learning template Skills Online BSL - Judith Sanders MultiMedia & e-Learning","headline":"E-Learning template Skills Online BSL","author":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/#author"},"publisher":{"@id":"https:\/\/judithsanders.nl\/website\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2017\/08\/featured_BSL_templateSkillsOnline.jpg","width":1000,"height":600},"datePublished":"2017-08-01T18:42:12+01:00","dateModified":"2024-04-24T15:16:36+01:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/2017\/08\/01\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\/#webpage"},"isPartOf":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/2017\/08\/01\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\/#webpage"},"articleSection":"E-Learning"},{"@type":"BreadcrumbList","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2017\/08\/01\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website#listItem","position":1,"name":"Home","item":"https:\/\/judithsanders.nl\/website","nextItem":{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/category\/e-learning\/#listItem","name":"E-Learning"}},{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/category\/e-learning\/#listItem","position":2,"name":"E-Learning","item":"https:\/\/judithsanders.nl\/website\/index.php\/category\/e-learning\/","nextItem":{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2017\/08\/01\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\/#listItem","name":"E-Learning template Skills Online BSL"},"previousItem":{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2017\/08\/01\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\/#listItem","position":3,"name":"E-Learning template Skills Online BSL","previousItem":{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/category\/e-learning\/#listItem","name":"E-Learning"}}]},{"@type":"Organization","@id":"https:\/\/judithsanders.nl\/website\/#organization","name":"Judith Sanders MultiMedia & e-Learning","description":"Freelance e-Learning designer and developer Totaaloplossing e-Learning Naast mijn design competenties lever ik diverse nevendiensten die samen een allround servicepakket opleveren om alle e-Learning en andere diverse digitale projecten perfect op te kunnen leveren, al dan niet in partnership. Design wordt als \u00e9\u00e9n van de hoofddisciplines aangeboden, waarbij het eindresultaat gebruiksvriendelijk is en professioneel oogt. Het is intu\u00eftief en spreekt de beoogde doelgroep aan. Technisch ben ik competent en is er weinig wat niet kan in mijn beleving. Mocht het nodig zijn dan kan ik altijd nog iemand uit mijn netwerk inschakelen om het project extra kracht bij te zetten. Mijn toegevoegde waarde is luisteren naar uw wensen en deze optimaal vertalen naar het product van uw keuze.","url":"https:\/\/judithsanders.nl\/website\/","telephone":"+31652460068","logo":{"@type":"ImageObject","url":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2017\/08\/01\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\/#organizationLogo","width":1039,"height":1060},"image":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/2017\/08\/01\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\/#organizationLogo"},"sameAs":["https:\/\/www.linkedin.com\/in\/judithsanders\/"]},{"@type":"Person","@id":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/#author","url":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2017\/08\/01\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/fca062c59add9c0becf05d336fedb615de736cc5a007bc2c39f46bb848991a1b?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2017\/08\/01\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\/#webpage","url":"https:\/\/judithsanders.nl\/website\/index.php\/2017\/08\/01\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\/","name":"E-Learning template Skills Online BSL - Judith Sanders MultiMedia & e-Learning","description":"In opdracht van Bohn Stafleu van Loghum (BSL) mocht ik van scratch een geavanceerde en complete Articulate Storyline template maken voor het BSL leerplatform 'Skills Online'. Als uitgangspunt kreeg ik de inhoud van een nieuwe module (onderwerp 'Injecteren') in combinatie met de nieuwe e-Learning visie. Het design was vrij, er waren geen huisstijlregels om me","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/judithsanders.nl\/website\/#website"},"breadcrumb":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/2017\/08\/01\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\/#breadcrumblist"},"author":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/#author"},"creator":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2017\/08\/featured_BSL_templateSkillsOnline.jpg","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2017\/08\/01\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\/#mainImage","width":1000,"height":600},"primaryImageOfPage":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/2017\/08\/01\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\/#mainImage"},"datePublished":"2017-08-01T18:42:12+01:00","dateModified":"2024-04-24T15:16:36+01:00"},{"@type":"WebSite","@id":"https:\/\/judithsanders.nl\/website\/#website","url":"https:\/\/judithsanders.nl\/website\/","name":"Judith Sanders MultiMedia & e-Learning","description":"Freelance e-Learning designer and developer","inLanguage":"en-US","publisher":{"@id":"https:\/\/judithsanders.nl\/website\/#organization"}}]},"og:locale":"en_US","og:site_name":"Judith Sanders MultiMedia &amp; e-Learning - Freelance e-Learning designer and developer","og:type":"article","og:title":"E-Learning template Skills Online BSL - Judith Sanders MultiMedia &amp; e-Learning","og:description":"In opdracht van Bohn Stafleu van Loghum (BSL) mocht ik van scratch een geavanceerde en complete Articulate Storyline template maken voor het BSL leerplatform 'Skills Online'. Als uitgangspunt kreeg ik de inhoud van een nieuwe module (onderwerp 'Injecteren') in combinatie met de nieuwe e-Learning visie. Het design was vrij, er waren geen huisstijlregels om me","og:url":"https:\/\/judithsanders.nl\/website\/index.php\/2017\/08\/01\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\/","og:image":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png","og:image:secure_url":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png","og:image:width":1039,"og:image:height":1060,"article:published_time":"2017-08-01T17:42:12+00:00","article:modified_time":"2024-04-24T14:16:36+00:00","twitter:card":"summary_large_image","twitter:title":"E-Learning template Skills Online BSL - Judith Sanders MultiMedia &amp; e-Learning","twitter:description":"In opdracht van Bohn Stafleu van Loghum (BSL) mocht ik van scratch een geavanceerde en complete Articulate Storyline template maken voor het BSL leerplatform 'Skills Online'. Als uitgangspunt kreeg ik de inhoud van een nieuwe module (onderwerp 'Injecteren') in combinatie met de nieuwe e-Learning visie. Het design was vrij, er waren geen huisstijlregels om me","twitter:image":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png"},"aioseo_meta_data":{"post_id":"3344","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-01-24 02:48:01","updated":"2025-06-04 18:48:05","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/judithsanders.nl\/website\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/judithsanders.nl\/website\/index.php\/category\/e-learning\/\" title=\"E-Learning\">E-Learning<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tE-Learning template Skills Online BSL\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/judithsanders.nl\/website"},{"label":"E-Learning","link":"https:\/\/judithsanders.nl\/website\/index.php\/category\/e-learning\/"},{"label":"E-Learning template Skills Online BSL","link":"https:\/\/judithsanders.nl\/website\/index.php\/2017\/08\/01\/e-learning-template-skillsonline-bohn-stafleu-van-loghum\/"}],"_links":{"self":[{"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/posts\/3344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/comments?post=3344"}],"version-history":[{"count":3,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/posts\/3344\/revisions"}],"predecessor-version":[{"id":5220,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/posts\/3344\/revisions\/5220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/media\/5216"}],"wp:attachment":[{"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/media?parent=3344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/categories?post=3344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/tags?post=3344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}