{"id":878,"date":"2011-08-29T16:35:56","date_gmt":"2011-08-29T15:35:56","guid":{"rendered":"http:\/\/www.judithsanders.nl\/site\/?p=878"},"modified":"2011-08-29T16:35:56","modified_gmt":"2011-08-29T15:35:56","slug":"website-sip-hofstede","status":"publish","type":"post","link":"https:\/\/judithsanders.nl\/website\/index.php\/2011\/08\/29\/website-sip-hofstede\/","title":{"rendered":"Website Sip Hofstede"},"content":{"rendered":"<p>Sip Hofstede is een veelzijdig kunstenaar. Vooral bedreven in schilderkunst en architectuur (-in en exterieuren) heeft hij zijn sporen wel verdiend in de afgelopen 25 jaar. Deze site is gemaakt als een live non-stop draaiende expositie van zijn werk en dient als kennismaking met zijn bijzondere en sprekende persoonlijkheid.<\/p>\n<ul>\n<li>Adobe Photoshop<\/li>\n<li>WordPress<\/li>\n<li>PHP \/ CSS<\/li>\n<li>HTML5<\/li>\n<\/ul>\n<p>2011 Ontwerp en ontwikkeling website.<\/p>\n<p>Website: <a title=\"Website Sip Hofstede\" href=\"http:\/\/www.siphofstede.nl\" target=\"_blank\" rel=\"noopener\">www.siphofstede.nl<\/a><\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" alt=\"SIPHOFSTEDE1\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2013\/02\/SIPHOFSTEDE1.jpg\" width=\"532\" height=\"300\" \/><br \/>\n<img decoding=\"async\" alt=\"SIPHOFSTEDE2\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2013\/02\/SIPHOFSTEDE2.jpg\" width=\"532\" height=\"300\" \/><br \/>\n<img decoding=\"async\" alt=\"SIPHOFSTEDE3\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2013\/02\/SIPHOFSTEDE3.jpg\" width=\"532\" height=\"300\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" alt=\"SIPHOFSTEDE4\" src=\"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2013\/02\/SIPHOFSTEDE4.jpg\" width=\"532\" height=\"300\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sip Hofstede is een veelzijdig kunstenaar. Vooral bedreven in schilderkunst en architectuur (-in en exterieuren) heeft hij zijn sporen wel&#8230; <\/p>\n<div class=\"art-el-more\"><a href=\"https:\/\/judithsanders.nl\/website\/index.php\/2011\/08\/29\/website-sip-hofstede\/\" class=\"art-link art-color-link art-w-chevron\">Read more<\/a><\/div>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[42],"tags":[],"class_list":["post-878","post","type-post","status-publish","format-standard","hentry","category-websites"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Sip Hofstede is een veelzijdig kunstenaar. Vooral bedreven in schilderkunst en architectuur (-in en exterieuren) heeft hij zijn sporen wel verdiend in de afgelopen 25 jaar. Deze site is gemaakt als een live non-stop draaiende expositie van zijn werk en dient als kennismaking met zijn bijzondere en sprekende persoonlijkheid. Adobe Photoshop Wordpress PHP \/ CSS\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"admin\"\/>\n\t<meta name=\"google-site-verification\" content=\"WO6NTrPSlDMSbKVdm2D1-_LuA9xh_r0XoPxxl90knfQ\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/judithsanders.nl\/website\/index.php\/2011\/08\/29\/website-sip-hofstede\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_US\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Judith Sanders MultiMedia &amp; e-Learning - Freelance e-Learning designer and developer\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Website Sip Hofstede - Judith Sanders MultiMedia &amp; e-Learning\" \/>\n\t\t<meta property=\"og:description\" content=\"Sip Hofstede is een veelzijdig kunstenaar. Vooral bedreven in schilderkunst en architectuur (-in en exterieuren) heeft hij zijn sporen wel verdiend in de afgelopen 25 jaar. Deze site is gemaakt als een live non-stop draaiende expositie van zijn werk en dient als kennismaking met zijn bijzondere en sprekende persoonlijkheid. Adobe Photoshop Wordpress PHP \/ CSS\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/judithsanders.nl\/website\/index.php\/2011\/08\/29\/website-sip-hofstede\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1039\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1060\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2011-08-29T15:35:56+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2011-08-29T15:35:56+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Website Sip Hofstede - Judith Sanders MultiMedia &amp; e-Learning\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Sip Hofstede is een veelzijdig kunstenaar. Vooral bedreven in schilderkunst en architectuur (-in en exterieuren) heeft hij zijn sporen wel verdiend in de afgelopen 25 jaar. Deze site is gemaakt als een live non-stop draaiende expositie van zijn werk en dient als kennismaking met zijn bijzondere en sprekende persoonlijkheid. Adobe Photoshop Wordpress PHP \/ CSS\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2011\\\/08\\\/29\\\/website-sip-hofstede\\\/#blogposting\",\"name\":\"Website Sip Hofstede - Judith Sanders MultiMedia & e-Learning\",\"headline\":\"Website Sip Hofstede\",\"author\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/www.judithsanders.nl\\\/site\\\/wp-content\\\/uploads\\\/2013\\\/02\\\/SIPHOFSTEDE1.jpg\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2011\\\/08\\\/29\\\/website-sip-hofstede\\\/#articleImage\"},\"datePublished\":\"2011-08-29T16:35:56+01:00\",\"dateModified\":\"2011-08-29T16:35:56+01:00\",\"inLanguage\":\"en-US\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2011\\\/08\\\/29\\\/website-sip-hofstede\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2011\\\/08\\\/29\\\/website-sip-hofstede\\\/#webpage\"},\"articleSection\":\"Websites\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2011\\\/08\\\/29\\\/website-sip-hofstede\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/judithsanders.nl\\\/website\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/category\\\/websites\\\/#listItem\",\"name\":\"Websites\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/category\\\/websites\\\/#listItem\",\"position\":2,\"name\":\"Websites\",\"item\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/category\\\/websites\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2011\\\/08\\\/29\\\/website-sip-hofstede\\\/#listItem\",\"name\":\"Website Sip Hofstede\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2011\\\/08\\\/29\\\/website-sip-hofstede\\\/#listItem\",\"position\":3,\"name\":\"Website Sip Hofstede\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/category\\\/websites\\\/#listItem\",\"name\":\"Websites\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#organization\",\"name\":\"Judith Sanders MultiMedia & e-Learning\",\"description\":\"Freelance e-Learning designer and developer Totaaloplossing e-Learning Naast mijn design competenties lever ik diverse nevendiensten die samen een allround servicepakket opleveren om alle e-Learning en andere diverse digitale projecten perfect op te kunnen leveren, al dan niet in partnership. Design wordt als \\u00e9\\u00e9n van de hoofddisciplines aangeboden, waarbij het eindresultaat gebruiksvriendelijk is en professioneel oogt. Het is intu\\u00eftief en spreekt de beoogde doelgroep aan. Technisch ben ik competent en is er weinig wat niet kan in mijn beleving. Mocht het nodig zijn dan kan ik altijd nog iemand uit mijn netwerk inschakelen om het project extra kracht bij te zetten. Mijn toegevoegde waarde is luisteren naar uw wensen en deze optimaal vertalen naar het product van uw keuze.\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/\",\"telephone\":\"+31652460068\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/logo_judithsanders_grijsverloop.png\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2011\\\/08\\\/29\\\/website-sip-hofstede\\\/#organizationLogo\",\"width\":1039,\"height\":1060},\"image\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2011\\\/08\\\/29\\\/website-sip-hofstede\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/judithsanders\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/#author\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2011\\\/08\\\/29\\\/website-sip-hofstede\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fca062c59add9c0becf05d336fedb615de736cc5a007bc2c39f46bb848991a1b?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"admin\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2011\\\/08\\\/29\\\/website-sip-hofstede\\\/#webpage\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2011\\\/08\\\/29\\\/website-sip-hofstede\\\/\",\"name\":\"Website Sip Hofstede - Judith Sanders MultiMedia & e-Learning\",\"description\":\"Sip Hofstede is een veelzijdig kunstenaar. Vooral bedreven in schilderkunst en architectuur (-in en exterieuren) heeft hij zijn sporen wel verdiend in de afgelopen 25 jaar. Deze site is gemaakt als een live non-stop draaiende expositie van zijn werk en dient als kennismaking met zijn bijzondere en sprekende persoonlijkheid. Adobe Photoshop Wordpress PHP \\\/ CSS\",\"inLanguage\":\"en-US\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/2011\\\/08\\\/29\\\/website-sip-hofstede\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/index.php\\\/author\\\/admin-judith24\\\/#author\"},\"datePublished\":\"2011-08-29T16:35:56+01:00\",\"dateModified\":\"2011-08-29T16:35:56+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#website\",\"url\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/\",\"name\":\"Judith Sanders MultiMedia & e-Learning\",\"description\":\"Freelance e-Learning designer and developer\",\"inLanguage\":\"en-US\",\"publisher\":{\"@id\":\"https:\\\/\\\/judithsanders.nl\\\/website\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Website Sip Hofstede - Judith Sanders MultiMedia & e-Learning","description":"Sip Hofstede is een veelzijdig kunstenaar. Vooral bedreven in schilderkunst en architectuur (-in en exterieuren) heeft hij zijn sporen wel verdiend in de afgelopen 25 jaar. Deze site is gemaakt als een live non-stop draaiende expositie van zijn werk en dient als kennismaking met zijn bijzondere en sprekende persoonlijkheid. Adobe Photoshop Wordpress PHP \/ CSS","canonical_url":"https:\/\/judithsanders.nl\/website\/index.php\/2011\/08\/29\/website-sip-hofstede\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"WO6NTrPSlDMSbKVdm2D1-_LuA9xh_r0XoPxxl90knfQ","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2011\/08\/29\/website-sip-hofstede\/#blogposting","name":"Website Sip Hofstede - Judith Sanders MultiMedia & e-Learning","headline":"Website Sip Hofstede","author":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/#author"},"publisher":{"@id":"https:\/\/judithsanders.nl\/website\/#organization"},"image":{"@type":"ImageObject","url":"http:\/\/www.judithsanders.nl\/site\/wp-content\/uploads\/2013\/02\/SIPHOFSTEDE1.jpg","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2011\/08\/29\/website-sip-hofstede\/#articleImage"},"datePublished":"2011-08-29T16:35:56+01:00","dateModified":"2011-08-29T16:35:56+01:00","inLanguage":"en-US","mainEntityOfPage":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/2011\/08\/29\/website-sip-hofstede\/#webpage"},"isPartOf":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/2011\/08\/29\/website-sip-hofstede\/#webpage"},"articleSection":"Websites"},{"@type":"BreadcrumbList","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2011\/08\/29\/website-sip-hofstede\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website#listItem","position":1,"name":"Home","item":"https:\/\/judithsanders.nl\/website","nextItem":{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/category\/websites\/#listItem","name":"Websites"}},{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/category\/websites\/#listItem","position":2,"name":"Websites","item":"https:\/\/judithsanders.nl\/website\/index.php\/category\/websites\/","nextItem":{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2011\/08\/29\/website-sip-hofstede\/#listItem","name":"Website Sip Hofstede"},"previousItem":{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2011\/08\/29\/website-sip-hofstede\/#listItem","position":3,"name":"Website Sip Hofstede","previousItem":{"@type":"ListItem","@id":"https:\/\/judithsanders.nl\/website\/index.php\/category\/websites\/#listItem","name":"Websites"}}]},{"@type":"Organization","@id":"https:\/\/judithsanders.nl\/website\/#organization","name":"Judith Sanders MultiMedia & e-Learning","description":"Freelance e-Learning designer and developer Totaaloplossing e-Learning Naast mijn design competenties lever ik diverse nevendiensten die samen een allround servicepakket opleveren om alle e-Learning en andere diverse digitale projecten perfect op te kunnen leveren, al dan niet in partnership. Design wordt als \u00e9\u00e9n van de hoofddisciplines aangeboden, waarbij het eindresultaat gebruiksvriendelijk is en professioneel oogt. Het is intu\u00eftief en spreekt de beoogde doelgroep aan. Technisch ben ik competent en is er weinig wat niet kan in mijn beleving. Mocht het nodig zijn dan kan ik altijd nog iemand uit mijn netwerk inschakelen om het project extra kracht bij te zetten. Mijn toegevoegde waarde is luisteren naar uw wensen en deze optimaal vertalen naar het product van uw keuze.","url":"https:\/\/judithsanders.nl\/website\/","telephone":"+31652460068","logo":{"@type":"ImageObject","url":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2011\/08\/29\/website-sip-hofstede\/#organizationLogo","width":1039,"height":1060},"image":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/2011\/08\/29\/website-sip-hofstede\/#organizationLogo"},"sameAs":["https:\/\/www.linkedin.com\/in\/judithsanders\/"]},{"@type":"Person","@id":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/#author","url":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2011\/08\/29\/website-sip-hofstede\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/fca062c59add9c0becf05d336fedb615de736cc5a007bc2c39f46bb848991a1b?s=96&d=mm&r=g","width":96,"height":96,"caption":"admin"}},{"@type":"WebPage","@id":"https:\/\/judithsanders.nl\/website\/index.php\/2011\/08\/29\/website-sip-hofstede\/#webpage","url":"https:\/\/judithsanders.nl\/website\/index.php\/2011\/08\/29\/website-sip-hofstede\/","name":"Website Sip Hofstede - Judith Sanders MultiMedia & e-Learning","description":"Sip Hofstede is een veelzijdig kunstenaar. Vooral bedreven in schilderkunst en architectuur (-in en exterieuren) heeft hij zijn sporen wel verdiend in de afgelopen 25 jaar. Deze site is gemaakt als een live non-stop draaiende expositie van zijn werk en dient als kennismaking met zijn bijzondere en sprekende persoonlijkheid. Adobe Photoshop Wordpress PHP \/ CSS","inLanguage":"en-US","isPartOf":{"@id":"https:\/\/judithsanders.nl\/website\/#website"},"breadcrumb":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/2011\/08\/29\/website-sip-hofstede\/#breadcrumblist"},"author":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/#author"},"creator":{"@id":"https:\/\/judithsanders.nl\/website\/index.php\/author\/admin-judith24\/#author"},"datePublished":"2011-08-29T16:35:56+01:00","dateModified":"2011-08-29T16:35:56+01:00"},{"@type":"WebSite","@id":"https:\/\/judithsanders.nl\/website\/#website","url":"https:\/\/judithsanders.nl\/website\/","name":"Judith Sanders MultiMedia & e-Learning","description":"Freelance e-Learning designer and developer","inLanguage":"en-US","publisher":{"@id":"https:\/\/judithsanders.nl\/website\/#organization"}}]},"og:locale":"en_US","og:site_name":"Judith Sanders MultiMedia &amp; e-Learning - Freelance e-Learning designer and developer","og:type":"article","og:title":"Website Sip Hofstede - Judith Sanders MultiMedia &amp; e-Learning","og:description":"Sip Hofstede is een veelzijdig kunstenaar. Vooral bedreven in schilderkunst en architectuur (-in en exterieuren) heeft hij zijn sporen wel verdiend in de afgelopen 25 jaar. Deze site is gemaakt als een live non-stop draaiende expositie van zijn werk en dient als kennismaking met zijn bijzondere en sprekende persoonlijkheid. Adobe Photoshop Wordpress PHP \/ CSS","og:url":"https:\/\/judithsanders.nl\/website\/index.php\/2011\/08\/29\/website-sip-hofstede\/","og:image":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png","og:image:secure_url":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png","og:image:width":1039,"og:image:height":1060,"article:published_time":"2011-08-29T15:35:56+00:00","article:modified_time":"2011-08-29T15:35:56+00:00","twitter:card":"summary_large_image","twitter:title":"Website Sip Hofstede - Judith Sanders MultiMedia &amp; e-Learning","twitter:description":"Sip Hofstede is een veelzijdig kunstenaar. Vooral bedreven in schilderkunst en architectuur (-in en exterieuren) heeft hij zijn sporen wel verdiend in de afgelopen 25 jaar. Deze site is gemaakt als een live non-stop draaiende expositie van zijn werk en dient als kennismaking met zijn bijzondere en sprekende persoonlijkheid. Adobe Photoshop Wordpress PHP \/ CSS","twitter:image":"https:\/\/judithsanders.nl\/website\/wp-content\/uploads\/2024\/04\/logo_judithsanders_grijsverloop.png"},"aioseo_meta_data":{"post_id":"878","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-01-23 23:18:02","updated":"2025-06-04 15:18:05","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/judithsanders.nl\/website\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/judithsanders.nl\/website\/index.php\/category\/websites\/\" title=\"Websites\">Websites<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tWebsite Sip Hofstede\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/judithsanders.nl\/website"},{"label":"Websites","link":"https:\/\/judithsanders.nl\/website\/index.php\/category\/websites\/"},{"label":"Website Sip Hofstede","link":"https:\/\/judithsanders.nl\/website\/index.php\/2011\/08\/29\/website-sip-hofstede\/"}],"_links":{"self":[{"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/posts\/878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/comments?post=878"}],"version-history":[{"count":0,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/posts\/878\/revisions"}],"wp:attachment":[{"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/media?parent=878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/categories?post=878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/judithsanders.nl\/website\/index.php\/wp-json\/wp\/v2\/tags?post=878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}